{"id":508,"date":"2021-08-25T13:33:02","date_gmt":"2021-08-25T13:33:02","guid":{"rendered":"https:\/\/architecturehub.liquid-themes.com\/elementor\/?page_id=508"},"modified":"2024-05-28T21:34:18","modified_gmt":"2024-05-28T18:34:18","slug":"projects","status":"publish","type":"page","link":"https:\/\/pantazelos.gr\/el\/projects\/","title":{"rendered":"Projects"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"508\" class=\"elementor elementor-508\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-73603eb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"73603eb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-44b6d58\" data-id=\"44b6d58\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7ceab62 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7ceab62\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7e656d3\" data-id=\"7e656d3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f3a290f elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"f3a290f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div id=\"ld-fancy-heading-6a97bd506f7cd\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<h6 class=\"ld-fh-element d-inline-block pos-rel  elementor-heading-title lqd-highlight-classic lqd-highlight-grow-left h6\"  > Projects<\/h6>\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fe107f4 elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"fe107f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div id=\"ld-fancy-heading-6a97bd50701c9\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<h1 class=\"ld-fh-element d-inline-block pos-rel  elementor-heading-title lqd-highlight-classic lqd-highlight-grow-left h2\"  > Explore <em class=\"h3 d-flex\">the collections.<\/em><\/h1>\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8a92308\" data-id=\"8a92308\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5ccb8bc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5ccb8bc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ca2102f\" data-id=\"ca2102f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-106cc89 elementor-widget elementor-widget-ld_portfolio\" data-id=\"106cc89\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ld_portfolio.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"lqd-pf-grid lqd-pf-grid-106cc89\">\t\t\t\r\n<div class=\"liquid-filter-items align-items-center justify-content-between\">\t\r\n\t<div class=\"liquid-filter-items-inner flex-grow-1\">\r\n\t\t\r\n\t\t\t\t\t<span class=\"liquid-filter-items-label  size-lg\">Filter by<\/span>\r\n\t\t\r\n\t\t<ul class=\"filter-list filter-list-inline       d-flex align-items-center hidden-xs hidden-sm\" id=\"lqd-pf-filter-6126469515f2d\">\r\n\t\t\t<li class=\"active\" data-filter=\"*\"><span>All<\/span><\/li>\r\n\t\t\t<li data-filter=\".lqd-f-67\"><span>\u03a1\u03b1\u03bc\u03b1\u03b6\u03ac\u03bd\u03b9<\/span><\/li><li data-filter=\".lqd-f-66\"><span>\u03a3\u03b5\u03c1\u03b2\u03b9\u03c1\u03af\u03c3\u03bc\u03b1\u03c4\u03bf\u03c2<\/span><\/li><li data-filter=\".lqd-f-65\"><span>\u03a3\u0395\u03a4<\/span><\/li><li data-filter=\".lqd-f-64\"><span>Stands Collection<\/span><\/li><li data-filter=\".lqd-f-63\"><span>Tableware Collection<\/span><\/li><li data-filter=\".lqd-f-53\"><span>\u03a3\u03b5\u03c4 \u0393\u03ac\u03bc\u03bf\u03c5<\/span><\/li>\t\t<\/ul>\r\n\r\n\t\t<div class=\"lqd-filter-dropdown visible-xs visible-sm\" data-form-options='{ \"dropdownAppendTo\": \"self\" }'>\r\n\t\t\t<select name=\"lqd-filter-dropdown-lqd-pf-filter-6126469515f2d\" id=\"lqd-filter-dropdown-lqd-pf-filter-6126469515f2d\">\r\n\t\t\t\t<option selected data-filter=\"*\" value=\"*\">All<\/option>\r\n\t\t\t\t<option data-filter=\".lqd-f-67\" value=\".lqd-f-67\">\u03a1\u03b1\u03bc\u03b1\u03b6\u03ac\u03bd\u03b9<\/option><option data-filter=\".lqd-f-66\" value=\".lqd-f-66\">\u03a3\u03b5\u03c1\u03b2\u03b9\u03c1\u03af\u03c3\u03bc\u03b1\u03c4\u03bf\u03c2<\/option><option data-filter=\".lqd-f-65\" value=\".lqd-f-65\">\u03a3\u0395\u03a4<\/option><option data-filter=\".lqd-f-64\" value=\".lqd-f-64\">Stands Collection<\/option><option data-filter=\".lqd-f-63\" value=\".lqd-f-63\">Tableware Collection<\/option><option data-filter=\".lqd-f-53\" value=\".lqd-f-53\">\u03a3\u03b5\u03c4 \u0393\u03ac\u03bc\u03bf\u03c5<\/option>\t\t\t<\/select>\r\n\t\t<\/div>\r\n\t\t\t\r\n\t\t\t\t<a  href=\"#\" class=\"elementor-button btn ws-nowrap btn-naked btn-icon-right btn-has-label\" >\n\t\t\t\t\t\t\t<span class=\"btn-txt\" data-text=\"See more\" >See more<\/span>\n\t\t\t\t\t\t<span class=\"btn-icon\"><i class=\"lqd-icn-ess icon-md-arrow-forward\"><\/i><\/span>\t\t<\/a>\n\t\t\t\t\t\t\t\t\r\n\t\t\t\r\n\t<\/div>\r\n<\/div><div id=\"lqd-pf-grid-106cc89\" class=\"lqd-pf-row row d-flex flex-wrap lqd-pf-grid-106cc89\" data-liquid-masonry=\"true\" data-masonry-options='{ \"layoutMode\": \"packery\", \"filtersID\": \"#lqd-pf-filter-6126469515f2d\" }'>\n<div class=\"lqd-pf-column col-md-4 col-sm-6 col-xs-12 col-sm-6 col-xs-12 masonry-item wedding-collection lqd-f-53\">\n\n\t<article id=\"post-2810\" class=\"lqd-pf-item lqd-pf-item-style-2 lqd-pf-overlay-bg-scale lqd-pf-dark pf-details-h-str post-2810 liquid-portfolio type-liquid-portfolio status-publish format-standard has-post-thumbnail hentry liquid-portfolio-category-wedding-collection\">\n\t\t<div class=\"lqd-pf-item-inner\">\n\n\t\t\t<div class=\"lqd-pf-img mb-3 pos-rel border-radius-6 overflow-hidden\">\n\t\t\t\t<figure>\n\t\t\t\t\t<figure class=\"w-100\"><img fetchpriority=\"high\" decoding=\"async\" width=\"667\" height=\"667\" src=\"https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/07\/G140906_0606-min.jpg\" class=\"w-100 wp-post-image\" alt=\"\" srcset=\"https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/07\/G140906_0606-min.jpg 667w, https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/07\/G140906_0606-min-300x300.jpg 300w, https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/07\/G140906_0606-min-150x150.jpg 150w, https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/07\/G140906_0606-min-12x12.jpg 12w, https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/07\/G140906_0606-min-320x320.jpg 320w\" sizes=\"(max-width: 667px) 100vw, 667px\" itemprop=\"image\" \/><\/figure>\t\t\t\t<\/figure>\n\t\t\t\t<span class=\"lqd-pf-overlay-bg lqd-overlay d-flex align-items-center justify-content-center\">\n\t\t\t\t\t<i class=\"\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\n\t\t\t<div class=\"lqd-pf-details\">\n\t\t\t\t\t\t\t\t<h2 class=\"lqd-pf-title mt-0 mb-1\">\u03a3\u03b5\u03c4 \u0393\u03ac\u03bc\u03bf\u03c5<\/h2>\t\t\t\t<ul class=\"reset-ul inline-nav lqd-pf-cat d-inline-flex pos-rel z-index-2\"><li><a href=\"https:\/\/pantazelos.gr\/el\/collections\/wedding-collection\/\">\u03a3\u03b5\u03c4 \u0393\u03ac\u03bc\u03bf\u03c5<\/a><\/li><\/ul>\n\t\t\t<\/div>\n\n\t\t\t<a href=\"https:\/\/pantazelos.gr\/el\/collections\/wedding-collection-2\/\"  class=\"lqd-overlay lqd-pf-overlay-link lqd-cc-icon-trigger\" ><\/a>\n\t\t<\/div>\n\t<\/article>\n\n<\/div>\n<div class=\"lqd-pf-column col-md-4 col-sm-6 col-xs-12 col-sm-6 col-xs-12 masonry-item tableware-collection lqd-f-63\">\n\n\t<article id=\"post-2673\" class=\"lqd-pf-item lqd-pf-item-style-2 lqd-pf-overlay-bg-scale lqd-pf-dark pf-details-h-str post-2673 liquid-portfolio type-liquid-portfolio status-publish format-standard has-post-thumbnail hentry liquid-portfolio-category-tableware-collection\">\n\t\t<div class=\"lqd-pf-item-inner\">\n\n\t\t\t<div class=\"lqd-pf-img mb-3 pos-rel border-radius-6 overflow-hidden\">\n\t\t\t\t<figure>\n\t\t\t\t\t<figure class=\"w-100\"><img decoding=\"async\" width=\"4401\" height=\"4401\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 4401 4401&#039;%2F%3E\" class=\"w-100 ld-lazyload wp-post-image\" alt=\"\" itemprop=\"image\" data-src=\"https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/05\/14094-min.jpg\" data-srcset=\"https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/05\/14094-min.jpg 4401w, https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/05\/14094-min-300x300.jpg 300w, https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/05\/14094-min-1024x1024.jpg 1024w, https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/05\/14094-min-150x150.jpg 150w, https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/05\/14094-min-12x12.jpg 12w, https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/05\/14094-min-1536x1536.jpg 1536w, https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/05\/14094-min-2048x2048.jpg 2048w, https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/05\/14094-min-320x320.jpg 320w, https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/05\/14094-min-760x760.jpg 760w, https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/05\/14094-min-800x800.jpg 800w, https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/05\/14094-min-100x100.jpg 100w\" data-sizes=\"(max-width: 4401px) 100vw, 4401px\" data-aspect=\"1\" \/><\/figure>\t\t\t\t<\/figure>\n\t\t\t\t<span class=\"lqd-pf-overlay-bg lqd-overlay d-flex align-items-center justify-content-center\">\n\t\t\t\t\t<i class=\"\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\n\t\t\t<div class=\"lqd-pf-details\">\n\t\t\t\t\t\t\t\t<h2 class=\"lqd-pf-title mt-0 mb-1\">Tableware Collection<\/h2>\t\t\t\t<ul class=\"reset-ul inline-nav lqd-pf-cat d-inline-flex pos-rel z-index-2\"><li><a href=\"https:\/\/pantazelos.gr\/el\/collections\/tableware-collection\/\">Tableware Collection<\/a><\/li><\/ul>\n\t\t\t<\/div>\n\n\t\t\t<a href=\"https:\/\/pantazelos.gr\/el\/collections\/tableware-collection\/\"  class=\"lqd-overlay lqd-pf-overlay-link lqd-cc-icon-trigger\" ><\/a>\n\t\t<\/div>\n\t<\/article>\n\n<\/div>\n<div class=\"lqd-pf-column col-md-4 col-sm-6 col-xs-12 col-sm-6 col-xs-12 masonry-item stands-collection lqd-f-64\">\n\n\t<article id=\"post-2672\" class=\"lqd-pf-item lqd-pf-item-style-2 lqd-pf-overlay-bg-scale lqd-pf-dark pf-details-h-str post-2672 liquid-portfolio type-liquid-portfolio status-publish format-standard has-post-thumbnail hentry liquid-portfolio-category-stands-collection\">\n\t\t<div class=\"lqd-pf-item-inner\">\n\n\t\t\t<div class=\"lqd-pf-img mb-3 pos-rel border-radius-6 overflow-hidden\">\n\t\t\t\t<figure>\n\t\t\t\t\t<figure class=\"w-100\"><img decoding=\"async\" width=\"2000\" height=\"2000\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2000 2000&#039;%2F%3E\" class=\"w-100 ld-lazyload wp-post-image\" alt=\"\" itemprop=\"image\" data-src=\"https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/05\/STAND-3_B-min-1.jpg\" data-srcset=\"https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/05\/STAND-3_B-min-1.jpg 2000w, https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/05\/STAND-3_B-min-1-300x300.jpg 300w, https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/05\/STAND-3_B-min-1-1024x1024.jpg 1024w, https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/05\/STAND-3_B-min-1-150x150.jpg 150w, https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/05\/STAND-3_B-min-1-12x12.jpg 12w, https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/05\/STAND-3_B-min-1-1536x1536.jpg 1536w, https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/05\/STAND-3_B-min-1-320x320.jpg 320w, https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/05\/STAND-3_B-min-1-760x760.jpg 760w, https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/05\/STAND-3_B-min-1-800x800.jpg 800w, https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/05\/STAND-3_B-min-1-100x100.jpg 100w\" data-sizes=\"(max-width: 2000px) 100vw, 2000px\" data-aspect=\"1\" \/><\/figure>\t\t\t\t<\/figure>\n\t\t\t\t<span class=\"lqd-pf-overlay-bg lqd-overlay d-flex align-items-center justify-content-center\">\n\t\t\t\t\t<i class=\"\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\n\t\t\t<div class=\"lqd-pf-details\">\n\t\t\t\t\t\t\t\t<h2 class=\"lqd-pf-title mt-0 mb-1\">Stands Collection<\/h2>\t\t\t\t<ul class=\"reset-ul inline-nav lqd-pf-cat d-inline-flex pos-rel z-index-2\"><li><a href=\"https:\/\/pantazelos.gr\/el\/collections\/stands-collection\/\">Stands Collection<\/a><\/li><\/ul>\n\t\t\t<\/div>\n\n\t\t\t<a href=\"https:\/\/pantazelos.gr\/el\/collections\/stands-collection\/\"  class=\"lqd-overlay lqd-pf-overlay-link lqd-cc-icon-trigger\" ><\/a>\n\t\t<\/div>\n\t<\/article>\n\n<\/div>\n<div class=\"lqd-pf-column col-md-4 col-sm-6 col-xs-12 col-sm-6 col-xs-12 masonry-item set-collection lqd-f-65\">\n\n\t<article id=\"post-2671\" class=\"lqd-pf-item lqd-pf-item-style-2 lqd-pf-overlay-bg-scale lqd-pf-dark pf-details-h-str post-2671 liquid-portfolio type-liquid-portfolio status-publish format-standard has-post-thumbnail hentry liquid-portfolio-category-set-collection\">\n\t\t<div class=\"lqd-pf-item-inner\">\n\n\t\t\t<div class=\"lqd-pf-img mb-3 pos-rel border-radius-6 overflow-hidden\">\n\t\t\t\t<figure>\n\t\t\t\t\t<figure class=\"w-100\"><img loading=\"lazy\" decoding=\"async\" width=\"3543\" height=\"3543\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 3543 3543&#039;%2F%3E\" class=\"w-100 ld-lazyload wp-post-image\" alt=\"\" itemprop=\"image\" data-src=\"https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/05\/0132-min.jpg\" data-srcset=\"https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/05\/0132-min.jpg 3543w, https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/05\/0132-min-300x300.jpg 300w, https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/05\/0132-min-1024x1024.jpg 1024w, https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/05\/0132-min-150x150.jpg 150w, https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/05\/0132-min-12x12.jpg 12w\" data-sizes=\"(max-width: 3543px) 100vw, 3543px\" data-aspect=\"1\" \/><\/figure>\t\t\t\t<\/figure>\n\t\t\t\t<span class=\"lqd-pf-overlay-bg lqd-overlay d-flex align-items-center justify-content-center\">\n\t\t\t\t\t<i class=\"\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\n\t\t\t<div class=\"lqd-pf-details\">\n\t\t\t\t\t\t\t\t<h2 class=\"lqd-pf-title mt-0 mb-1\">\u03a3\u0395\u03a4<\/h2>\t\t\t\t<ul class=\"reset-ul inline-nav lqd-pf-cat d-inline-flex pos-rel z-index-2\"><li><a href=\"https:\/\/pantazelos.gr\/el\/collections\/set-collection\/\">\u03a3\u0395\u03a4<\/a><\/li><\/ul>\n\t\t\t<\/div>\n\n\t\t\t<a href=\"https:\/\/pantazelos.gr\/el\/collections\/set-collection\/\"  class=\"lqd-overlay lqd-pf-overlay-link lqd-cc-icon-trigger\" ><\/a>\n\t\t<\/div>\n\t<\/article>\n\n<\/div>\n<div class=\"lqd-pf-column col-md-4 col-sm-6 col-xs-12 col-sm-6 col-xs-12 masonry-item serving-collection lqd-f-66\">\n\n\t<article id=\"post-2674\" class=\"lqd-pf-item lqd-pf-item-style-2 lqd-pf-overlay-bg-scale lqd-pf-dark pf-details-h-str post-2674 liquid-portfolio type-liquid-portfolio status-publish format-standard has-post-thumbnail hentry liquid-portfolio-category-serving-collection\">\n\t\t<div class=\"lqd-pf-item-inner\">\n\n\t\t\t<div class=\"lqd-pf-img mb-3 pos-rel border-radius-6 overflow-hidden\">\n\t\t\t\t<figure>\n\t\t\t\t\t<figure class=\"w-100\"><img loading=\"lazy\" decoding=\"async\" width=\"3000\" height=\"3000\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 3000 3000&#039;%2F%3E\" class=\"w-100 ld-lazyload wp-post-image\" alt=\"\" itemprop=\"image\" data-src=\"https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/05\/8812F-min.jpg\" data-srcset=\"https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/05\/8812F-min.jpg 3000w, https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/05\/8812F-min-300x300.jpg 300w, https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/05\/8812F-min-1024x1024.jpg 1024w, https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/05\/8812F-min-150x150.jpg 150w, https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/05\/8812F-min-12x12.jpg 12w, https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/05\/8812F-min-1536x1536.jpg 1536w, https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/05\/8812F-min-2048x2048.jpg 2048w, https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/05\/8812F-min-320x320.jpg 320w, https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/05\/8812F-min-760x760.jpg 760w, https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/05\/8812F-min-800x800.jpg 800w, https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/05\/8812F-min-100x100.jpg 100w\" data-sizes=\"(max-width: 3000px) 100vw, 3000px\" data-aspect=\"1\" \/><\/figure>\t\t\t\t<\/figure>\n\t\t\t\t<span class=\"lqd-pf-overlay-bg lqd-overlay d-flex align-items-center justify-content-center\">\n\t\t\t\t\t<i class=\"\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\n\t\t\t<div class=\"lqd-pf-details\">\n\t\t\t\t\t\t\t\t<h2 class=\"lqd-pf-title mt-0 mb-1\">\u03a3\u03b5\u03c1\u03b2\u03b9\u03c1\u03af\u03c3\u03bc\u03b1\u03c4\u03bf\u03c2<\/h2>\t\t\t\t<ul class=\"reset-ul inline-nav lqd-pf-cat d-inline-flex pos-rel z-index-2\"><li><a href=\"https:\/\/pantazelos.gr\/el\/collections\/serving-collection\/\">\u03a3\u03b5\u03c1\u03b2\u03b9\u03c1\u03af\u03c3\u03bc\u03b1\u03c4\u03bf\u03c2<\/a><\/li><\/ul>\n\t\t\t<\/div>\n\n\t\t\t<a href=\"https:\/\/pantazelos.gr\/el\/collections\/serving-collection\/\"  class=\"lqd-overlay lqd-pf-overlay-link lqd-cc-icon-trigger\" ><\/a>\n\t\t<\/div>\n\t<\/article>\n\n<\/div>\n<div class=\"lqd-pf-column col-md-4 col-sm-6 col-xs-12 col-sm-6 col-xs-12 masonry-item ramadan-collection lqd-f-67\">\n\n\t<article id=\"post-362\" class=\"lqd-pf-item lqd-pf-item-style-2 lqd-pf-overlay-bg-scale lqd-pf-dark pf-details-h-str post-362 liquid-portfolio type-liquid-portfolio status-publish format-standard has-post-thumbnail hentry liquid-portfolio-category-ramadan-collection\">\n\t\t<div class=\"lqd-pf-item-inner\">\n\n\t\t\t<div class=\"lqd-pf-img mb-3 pos-rel border-radius-6 overflow-hidden\">\n\t\t\t\t<figure>\n\t\t\t\t\t<figure class=\"w-100\"><img loading=\"lazy\" decoding=\"async\" width=\"3000\" height=\"3000\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 3000 3000&#039;%2F%3E\" class=\"w-100 ld-lazyload wp-post-image\" alt=\"\" itemprop=\"image\" data-src=\"https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/05\/STAND-612_GP-min.jpg\" data-srcset=\"https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/05\/STAND-612_GP-min.jpg 3000w, https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/05\/STAND-612_GP-min-300x300.jpg 300w, https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/05\/STAND-612_GP-min-1024x1024.jpg 1024w, https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/05\/STAND-612_GP-min-150x150.jpg 150w, https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/05\/STAND-612_GP-min-12x12.jpg 12w\" data-sizes=\"(max-width: 3000px) 100vw, 3000px\" data-aspect=\"1\" \/><\/figure>\t\t\t\t<\/figure>\n\t\t\t\t<span class=\"lqd-pf-overlay-bg lqd-overlay d-flex align-items-center justify-content-center\">\n\t\t\t\t\t<i class=\"\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\n\t\t\t<div class=\"lqd-pf-details\">\n\t\t\t\t\t\t\t\t<h2 class=\"lqd-pf-title mt-0 mb-1\">\u03a1\u03b1\u03bc\u03b1\u03b6\u03ac\u03bd\u03b9<\/h2>\t\t\t\t<ul class=\"reset-ul inline-nav lqd-pf-cat d-inline-flex pos-rel z-index-2\"><li><a href=\"https:\/\/pantazelos.gr\/el\/collections\/ramadan-collection\/\">\u03a1\u03b1\u03bc\u03b1\u03b6\u03ac\u03bd\u03b9<\/a><\/li><\/ul>\n\t\t\t<\/div>\n\n\t\t\t<a href=\"https:\/\/pantazelos.gr\/el\/collections\/ramadan-collection\/\"  class=\"lqd-overlay lqd-pf-overlay-link lqd-cc-icon-trigger\" ><\/a>\n\t\t<\/div>\n\t<\/article>\n\n<\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a2b8b95 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a2b8b95\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ed5500b\" data-id=\"ed5500b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8d2155c elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"8d2155c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div id=\"ld-fancy-heading-6a97bd5092639\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<h2 class=\"ld-fh-element d-inline-block pos-rel  elementor-heading-title lqd-highlight-classic lqd-highlight-grow-left h2\"  > Are you interested? \n<em>Let\u2019s talk.<\/em><\/h2>\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f6a2ce0 elementor-widget elementor-widget-ld_button\" data-id=\"f6a2ce0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ld_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/pantazelos.gr\/el\/contact\/\"class=\"elementor-button btn btn-solid btn-xlg btn-icon-shaped btn-has-label\"\t\t\t>\n\t\t\t\t\t\t\t\t\t<span data-text=\"Let\u2019s make a contact\" class=\"btn-txt\">\n\t\t\t\t\t\tLet\u2019s make a contact\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Projects Explore the collections. Filter by All Ramadan Collection Serving Collection Set Collection Stands Collection Tableware Collection Wedding Collection AllRamadan CollectionServing CollectionSet CollectionStands CollectionTableware CollectionWedding Collection See more Tableware Collection Tableware Collection Stands Collection Stands Collection Set Collection Set Collection Serving Collection Serving Collection Ramadan Collection Ramadan Collection Minimalism Wedding Collection Are you interested? Let\u2019s [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-508","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Projects | Pantazelos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pantazelos.gr\/el\/projects\/\" \/>\n<meta property=\"og:locale\" content=\"el_GR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Projects | Pantazelos\" \/>\n<meta property=\"og:description\" content=\"Projects Explore the collections. Filter by All Ramadan Collection Serving Collection Set Collection Stands Collection Tableware Collection Wedding Collection AllRamadan CollectionServing CollectionSet CollectionStands CollectionTableware CollectionWedding Collection See more Tableware Collection Tableware Collection Stands Collection Stands Collection Set Collection Set Collection Serving Collection Serving Collection Ramadan Collection Ramadan Collection Minimalism Wedding Collection Are you interested? Let\u2019s [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pantazelos.gr\/el\/projects\/\" \/>\n<meta property=\"og:site_name\" content=\"Pantazelos\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-28T18:34:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/03\/01-1.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u0395\u03ba\u03c4\u03b9\u03bc\u03ce\u03bc\u03b5\u03bd\u03bf\u03c2 \u03c7\u03c1\u03cc\u03bd\u03bf\u03c2 \u03b1\u03bd\u03ac\u03b3\u03bd\u03c9\u03c3\u03b7\u03c2\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 \u03bb\u03b5\u03c0\u03c4\u03ac\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/pantazelos.gr\/projects\/\",\"url\":\"https:\/\/pantazelos.gr\/projects\/\",\"name\":\"Projects | Pantazelos\",\"isPartOf\":{\"@id\":\"https:\/\/pantazelos.gr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/pantazelos.gr\/projects\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/pantazelos.gr\/projects\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/03\/01-1.jpg\",\"datePublished\":\"2021-08-25T13:33:02+00:00\",\"dateModified\":\"2024-05-28T18:34:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/pantazelos.gr\/projects\/#breadcrumb\"},\"inLanguage\":\"el\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/pantazelos.gr\/projects\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"el\",\"@id\":\"https:\/\/pantazelos.gr\/projects\/#primaryimage\",\"url\":\"https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/03\/01-1.jpg\",\"contentUrl\":\"https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/03\/01-1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/pantazelos.gr\/projects\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/pantazelos.gr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projects\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/pantazelos.gr\/#website\",\"url\":\"https:\/\/pantazelos.gr\/\",\"name\":\"Pantazelos\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/pantazelos.gr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/pantazelos.gr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"el\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/pantazelos.gr\/#organization\",\"name\":\"Pantazelos\",\"url\":\"https:\/\/pantazelos.gr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"el\",\"@id\":\"https:\/\/pantazelos.gr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/02\/Pantazelos_logo-3-1.png\",\"contentUrl\":\"https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/02\/Pantazelos_logo-3-1.png\",\"width\":600,\"height\":311,\"caption\":\"Pantazelos\"},\"image\":{\"@id\":\"https:\/\/pantazelos.gr\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Projects | Pantazelos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pantazelos.gr\/el\/projects\/","og_locale":"el_GR","og_type":"article","og_title":"Projects | Pantazelos","og_description":"Projects Explore the collections. Filter by All Ramadan Collection Serving Collection Set Collection Stands Collection Tableware Collection Wedding Collection AllRamadan CollectionServing CollectionSet CollectionStands CollectionTableware CollectionWedding Collection See more Tableware Collection Tableware Collection Stands Collection Stands Collection Set Collection Set Collection Serving Collection Serving Collection Ramadan Collection Ramadan Collection Minimalism Wedding Collection Are you interested? Let\u2019s [&hellip;]","og_url":"https:\/\/pantazelos.gr\/el\/projects\/","og_site_name":"Pantazelos","article_modified_time":"2024-05-28T18:34:18+00:00","og_image":[{"url":"https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/03\/01-1.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"\u0395\u03ba\u03c4\u03b9\u03bc\u03ce\u03bc\u03b5\u03bd\u03bf\u03c2 \u03c7\u03c1\u03cc\u03bd\u03bf\u03c2 \u03b1\u03bd\u03ac\u03b3\u03bd\u03c9\u03c3\u03b7\u03c2":"2 \u03bb\u03b5\u03c0\u03c4\u03ac"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/pantazelos.gr\/projects\/","url":"https:\/\/pantazelos.gr\/projects\/","name":"Projects | Pantazelos","isPartOf":{"@id":"https:\/\/pantazelos.gr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pantazelos.gr\/projects\/#primaryimage"},"image":{"@id":"https:\/\/pantazelos.gr\/projects\/#primaryimage"},"thumbnailUrl":"https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/03\/01-1.jpg","datePublished":"2021-08-25T13:33:02+00:00","dateModified":"2024-05-28T18:34:18+00:00","breadcrumb":{"@id":"https:\/\/pantazelos.gr\/projects\/#breadcrumb"},"inLanguage":"el","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pantazelos.gr\/projects\/"]}]},{"@type":"ImageObject","inLanguage":"el","@id":"https:\/\/pantazelos.gr\/projects\/#primaryimage","url":"https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/03\/01-1.jpg","contentUrl":"https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/03\/01-1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/pantazelos.gr\/projects\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/pantazelos.gr\/"},{"@type":"ListItem","position":2,"name":"Projects"}]},{"@type":"WebSite","@id":"https:\/\/pantazelos.gr\/#website","url":"https:\/\/pantazelos.gr\/","name":"Pantazelos","description":"","publisher":{"@id":"https:\/\/pantazelos.gr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pantazelos.gr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"el"},{"@type":"Organization","@id":"https:\/\/pantazelos.gr\/#organization","name":"Pantazelos","url":"https:\/\/pantazelos.gr\/","logo":{"@type":"ImageObject","inLanguage":"el","@id":"https:\/\/pantazelos.gr\/#\/schema\/logo\/image\/","url":"https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/02\/Pantazelos_logo-3-1.png","contentUrl":"https:\/\/pantazelos.gr\/wp-content\/uploads\/2024\/02\/Pantazelos_logo-3-1.png","width":600,"height":311,"caption":"Pantazelos"},"image":{"@id":"https:\/\/pantazelos.gr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/pantazelos.gr\/el\/wp-json\/wp\/v2\/pages\/508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pantazelos.gr\/el\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/pantazelos.gr\/el\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/pantazelos.gr\/el\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pantazelos.gr\/el\/wp-json\/wp\/v2\/comments?post=508"}],"version-history":[{"count":6,"href":"https:\/\/pantazelos.gr\/el\/wp-json\/wp\/v2\/pages\/508\/revisions"}],"predecessor-version":[{"id":2808,"href":"https:\/\/pantazelos.gr\/el\/wp-json\/wp\/v2\/pages\/508\/revisions\/2808"}],"wp:attachment":[{"href":"https:\/\/pantazelos.gr\/el\/wp-json\/wp\/v2\/media?parent=508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}